{"id":2360,"date":"2018-05-14T19:30:46","date_gmt":"2018-05-14T17:30:46","guid":{"rendered":"http:\/\/electro-strasbourg.eu\/blog\/?p=2360"},"modified":"2018-05-14T19:30:46","modified_gmt":"2018-05-14T17:30:46","slug":"stages-dete-acousmatique-musiques-et-recherches-en-belgique","status":"publish","type":"post","link":"https:\/\/electro-strasbourg.eu\/blog\/2018\/05\/stages-dete-acousmatique-musiques-et-recherches-en-belgique\/","title":{"rendered":"Stages d&rsquo;\u00e9t\u00e9 Acousmatique \u2013 Musiques et Recherches en Belgique"},"content":{"rendered":"<h1 class=\"null\"><span class=\"element\"><strong>STAGES D&rsquo;ETE\u00a0<\/strong><\/span><\/h1>\n<p>Cet \u00e9t\u00e9, venez vous mettre au vert \u00e0 Ohain (Belgique) pendant les stages d&rsquo;\u00e9t\u00e9 de Musiques &amp;\u00a0Recherches et d\u00e9couvrez la musique acousmatique sous toutes ses coutures. De la programmation sur Max \u00e0 la chasse au sons en balade \u00e0 v\u00e9lo\u00a0en passant par la manipulation de bandes magn\u00e9tiques, vous saurez tout..<\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5609-stage-max-for-beginners\" target=\"_blank\" rel=\"noopener\">MAX POUR DEBUTANTS\u00a0<\/a><\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5610-max-stage-level-ii\" target=\"_blank\" rel=\"noopener\">MAX NIVEAU 2<\/a><\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5611-stage-qvous-avez-dit-acousmatiqueq\" target=\"_blank\" rel=\"noopener\">VOUS AVEZ DIT ACOUSMATIQUE ?<\/a><\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5612-2017-11-27-11-02-52\" target=\"_blank\" rel=\"noopener\">COMPOSITION EN STUDIO ANALOGIQUE<\/a><\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5613-2017-11-27-12-04-02\" target=\"_blank\" rel=\"noopener\">INTERPRETATION SPATIALISEE DES MUSIQUES ACOUSMATIQUES<\/a><\/p>\n<p><a href=\"http:\/\/www.musiques-recherches.be\/fr\/agenda\/concert-acousmatique\/item\/5629-2018-05-11-11-00-30\" target=\"_blank\" rel=\"noopener\">VELO ET MUSIQUE ACOUSMATIQUE<\/a><\/p>\n<p><iframe loading=\"lazy\" title=\"stages 2013\" src=\"https:\/\/player.vimeo.com\/video\/76591768?dnt=1&amp;app_id=122963\" width=\"474\" height=\"267\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n<p><strong><span class=\"field_information value\">INFOS<\/span><\/strong><\/p>\n<p><span class=\"field_information value\">.Contacts ?<br \/>\n<a href=\"http:\/\/www.musiques-recherches.be\/\" target=\"_blank\" rel=\"noopener\">www.musiques-recherches.be<\/a><br \/>\n<span id=\"email_0\"><a href=\"mailto:info@musiques-recherches.be\">info@musiques-recherches.be<\/a><\/span><br \/>\nT + 32 (0)2 3544368<br \/>\nF + 32 (0)2 3510094<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>STAGES D&rsquo;ETE\u00a0 Cet \u00e9t\u00e9, venez vous mettre au vert \u00e0 Ohain (Belgique) pendant les stages d&rsquo;\u00e9t\u00e9 de Musiques &amp;\u00a0Recherches et d\u00e9couvrez la musique acousmatique sous toutes ses coutures. De la programmation sur Max \u00e0 la chasse au sons en balade \u00e0 v\u00e9lo\u00a0en passant par la manipulation de bandes magn\u00e9tiques, vous saurez tout.. MAX POUR DEBUTANTS\u00a0 &hellip; <a href=\"https:\/\/electro-strasbourg.eu\/blog\/2018\/05\/stages-dete-acousmatique-musiques-et-recherches-en-belgique\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Stages d&rsquo;\u00e9t\u00e9 Acousmatique \u2013 Musiques et Recherches en Belgique<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26,40],"tags":[49,28,30],"class_list":["post-2360","post","type-post","status-publish","format-standard","hentry","category-concours-appels","category-electro","tag-acousmatique","tag-composition","tag-electroacoustique"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3WkX1-C4","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/posts\/2360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":1,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/posts\/2360\/revisions"}],"predecessor-version":[{"id":2361,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/posts\/2360\/revisions\/2361"}],"wp:attachment":[{"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/media?parent=2360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/categories?post=2360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/electro-strasbourg.eu\/blog\/wp-json\/wp\/v2\/tags?post=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}